{"id":41028,"date":"2023-11-06T11:46:00","date_gmt":"2023-11-06T17:46:00","guid":{"rendered":"https:\/\/www.project44.com\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/"},"modified":"2024-09-06T11:27:03","modified_gmt":"2024-09-06T16:27:03","slug":"project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet","status":"publish","type":"press-release","link":"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/","title":{"rendered":"Project44 wird im Gartner\u00ae Peer Insights\u2122 \u201eVoice of the Customer\u201c Bericht als \u201e2023 Customers\u2019 Choice\u201c bezeichnet"},"content":{"rendered":"\n<p class=\"is-style-intro wp-block-paragraph\"><em>Der Bericht, der direkte Benutzereinblicke in Echtzeit-Transport-Transparenz-Plattformen bietet, zeigt, dass 94\u00a0% der Benutzer bereit sind, project44 zu empfehlen. <\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>CHICAGO, <\/strong>6. November 2023 &#8211;\u202f<a href=\"https:\/\/c212.net\/c\/link\/?t=0&amp;l=en&amp;o=3985745-1&amp;h=1259879904&amp;u=https%3A%2F%2Fwww.project44.com%2F&amp;a=project44\" target=\"_blank\" rel=\"noreferrer noopener\">project44<\/a>, die f\u00fchrende Supply-Chain-Transparenz-Plattform, gab heute bekannt, dass project44 in den Customers\u2019 Choice Quadrant des 2023er Gartner Peer Insight \u201eVoice of the Customer\u201c Berichts aufgenommen wurde. Dies ist ein einflussreicher Bericht, der wichtige Erkenntnisse f\u00fcr IT-Kaufentscheidungen liefern soll. Der 2023 Gartner Peer Insight \u201eVoice of the Customer\u201c Bericht nannte project44 basierend auf der Gesamterfahrung, dem Benutzerinteresse und den Akzeptanzraten einen Customer-Choice-Anbieter. Project44 ist der einzige Anbieter, der im Magic Quadrant for Real-Time Transportation Visibility Platforms (RTTVP) als Leader bezeichnet wird und mit der Gartner Peer Insights Customer-Choice-Auszeichnung ausgezeichnet wurde. <\/p>\n\n<p class=\"wp-block-paragraph\">F\u00fcnf Anbieter von Transport-Transparenz-Plattformen erf\u00fcllten die Gartner-Zulassungskriterien f\u00fcr die Aufnahme in den Bericht. Nur zwei wurden als Customer-Choice-Anbieter bezeichnet, wobei project44 den h\u00f6chsten Rang erreichte. Kunden gaben project44 au\u00dfergew\u00f6hnlich gute Bewertungen f\u00fcr Produktfunktionen und f\u00fcr die Vertrieb, Bereitstellung und Support-Erfahrung, wobei 94 % der Benutzer ihre Bereitschaft \u00e4u\u00dferten, die project44-Plattform auf Grundlage von 141 Gesamtbewertungen zum 31. August 2023 an Kollegen zu empfehlen. Project44 war nicht nur die Kundenwahl, sondern wies auch die globalste Pr\u00e4senz der im Bericht genannten Plattformen auf, die eine starke globale Lieferkettentiefe und -breite repr\u00e4sentieren. <\/p>\n\n<p class=\"wp-block-paragraph\">Die 2023 Gartner Peer Insights \u201eVoice of the Customer\u201c ist eine kostenlose Peer-Review- und Rating-Plattform, die f\u00fcr Entscheider von Unternehmenssoftware und -services entwickelt wurde. Bewertungen werden nach Produkten in M\u00e4rkten organisiert, die von Gartner Research in Magic Quadrant und Market Guide-Dokumenten definiert wurden. Der Bericht \u201eVoice of the Customer\u201c umfasst Anbieter, die Produkte in einem bestimmten Markt gelistet haben (siehe Gartner Peer Insights Listing Guidelines hier) und \u00fcber den 18-monatigen Analysezeitraum 20 oder mehr qualifizierte Bewertungen sowie 15 oder mehr Bewertungen f\u00fcr die Unterbewertungen \u201eCapabilities\u201c und \u201eSupport\/Delivery\u201c erhalten haben.<a href=\"https:\/\/blogs.gartner.com\/reviews-pages\/gartner-peer-insights-voice-of-the-customer-methodology-3-0\/\" target=\"_blank\" rel=\"noreferrer noopener\">1<\/a> Anbieter, die im oberen rechten Quadranten des \u201eVoice of the Customer\u201c-Quadranten platziert sind, werden mit der Gartner Peer Insights Customer-Choice-Auszeichnung ausgezeichnet, die mit einem Customer-Choice-Abzeichen gekennzeichnet ist. Die anerkannten Anbieter erf\u00fcllen oder \u00fcbertreffen sowohl die marktdurchschnittliche Gesamterfahrung als auch das marktdurchschnittliche Nutzerinteresse und die Nutzerakzeptanz. <\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/get.project44.com\/2023-gartner-voice-of-customer-report\/?utm_source=project44&amp;utm_medium=press_release&amp;utm_campaign=voc\" target=\"_blank\" rel=\"noreferrer noopener\">Laden Sie eine kostenlose Kopie des Gartner Peer Insights Voice of the Customer Report herunter<\/a> <\/p>\n\n<p class=\"wp-block-paragraph\">\u201eProject44 wurde im vergangenen Jahr mit zahlreichen Preisen und Anerkennungen ausgezeichnet\u201c, sagte Jett McCandless, Gr\u00fcnder und CEO von project44. \u201eUnser Team ist dankbar f\u00fcr die Anerkennung, aber wir freuen uns besonders \u00fcber Empfehlungen von Supply-Chain-Experten, die unsere Echtzeit-Transparenz-Plattform t\u00e4glich nutzen. Unsere Mission ist es, Lieferketten funktionieren zu lassen; unsere Kunden sind unsere gesch\u00e4tzten Partner bei der L\u00f6sung von Supply-Chain-Problemen, um sicherzustellen, dass die Wirtschaft und Einzelpersonen die Produkte und Dienstleistungen erhalten, von denen sie abh\u00e4ngen.\u201c <\/p>\n\n<p class=\"wp-block-paragraph\">Die Pandemie wies auf Schwachstellen in der Lieferkette hin und unterstrich die Notwendigkeit einer Echtzeit-Transparenz \u00fcber alle Transportarten. Als sich die Lieferketten in der Folge stabilisierten, konzentrierten sich F\u00fchrungskr\u00e4fte darauf, widerstandsf\u00e4higere Netzwerke zu schaffen, die Reaktionsgeschwindigkeit zu beschleunigen und eine h\u00f6here Kosteneffizienz zu erzielen. Es ist kein Zufall, dass project44 ein Blockbuster-Gesch\u00e4ftsjahr 2023 erlebte, als Kunden aus verschiedenen Branchen und auf der ganzen Welt versuchten, Echtzeit-Transport-Transparenzl\u00f6sungen zu verbessern. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Hier sind einige Peer Reviews, die in diesem Bericht enthalten sind: <\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.gartner.com\/reviews\/market\/real-time-transportation-visibility-platforms\/vendor\/project44\/product\/project44-movement\/review\/view\/4883884\" target=\"_blank\" rel=\"noreferrer noopener\">&#8222;Lieferkettentransparenz mit P44\u202f&#8220;<\/a> <\/p>\n\n<p class=\"wp-block-paragraph\">\u201eWie bei jedem anderen Produkt ist die Schl\u00fcsselst\u00e4rke von p44 der erstklassige Kundenservice, der mit der bereitgestellten Technologie verbunden ist. W\u00e4hrend der gesamten IT-Implementierung, des Carrier-Onboardings, der Schulung und des t\u00e4glichen Supports waren die Teams von p44 immer verf\u00fcgbar und unnachgiebig, um jedes Problem zu l\u00f6sen.\u201c <\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.gartner.com\/reviews\/market\/real-time-transportation-visibility-platforms\/vendor\/project44\/product\/project44-movement\/review\/view\/4856604\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eErweiterte Visibilit\u00e4tsplattform \u2013 project44\u201c<\/a> <\/p>\n\n<p class=\"wp-block-paragraph\">\u201eProject44 Movement bietet eine umfassende L\u00f6sung f\u00fcr Unternehmen, die ihre Logistik- und Supply-Chain-Management-F\u00e4higkeiten verbessern m\u00f6chten. Es ist eine der gr\u00f6\u00dften weltweit f\u00fchrenden Visibilit\u00e4tsplattformen. Es bietet Echtzeit-Transparenz und eine optimierte Zusammenarbeit, was zu betrieblicher Effizienz f\u00fchrt.\u201c <\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.gartner.com\/reviews\/market\/real-time-transportation-visibility-platforms\/vendor\/project44\/product\/project44-movement\/review\/view\/4533406\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eDie beste Transparenzplattform auf dem Markt.\u201c<\/a> <\/p>\n\n<p class=\"wp-block-paragraph\">\u201eProject44 hat Zugriff auf eine Vielzahl von Daten \u00fcber verschiedene Transportmittel hinweg und macht den Wert, der durch das System erzeugt wird, sehr viel gr\u00f6\u00dfer.\u201c <\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.gartner.com\/reviews\/market\/real-time-transportation-visibility-platforms\/vendor\/project44\/product\/project44-movement\/review\/view\/4535128\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eP44 Transparenz ist ein Game Changer\u201c<\/a> <\/p>\n\n<p class=\"wp-block-paragraph\">\u201eDie project44 Transparenzplattform hat f\u00fcr uns die Spielregeln ver\u00e4ndert!\u201c <\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.gartner.com\/reviews\/market\/real-time-transportation-visibility-platforms\/vendor\/project44\/product\/project44-movement\/review\/view\/4535228\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eP44 f\u00fchrend in der Gruppe f\u00fcr End-to-End-Transparenz \u00fcber verschiedene Modi hinweg\u201c<\/a> <\/p>\n\n<p class=\"wp-block-paragraph\">\u201eProject44 hat enorm zur Importtransparenz beigetragen. Es hat uns geholfen, genauere ETAs bereitzustellen und so unsere Kundenerfahrung zu verbessern.\u201c <\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.gartner.com\/reviews\/market\/real-time-transportation-visibility-platforms\/vendor\/project44\/product\/project44-movement\/review\/view\/4618584\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eProject44 ist unsere One-Stop-L\u00f6sung f\u00fcr alle unsere Transparenz-Anforderungen.\u201c<\/a> <\/p>\n\n<p class=\"wp-block-paragraph\">\u201eDie Plattform ist solide und liefert uns rund um die Uhr genaue Echtzeitinformationen. project44 verf\u00fcgt \u00fcber eine umfassende Datenbank an Expertenressourcen, die in jeder Phase der Implementierung und des laufenden Supports helfen.\u201c <\/p>\n\n<p class=\"wp-block-paragraph\">Project44 definiert die Kategorie Transport Visibility Platform neu mit Innovationen, die auf dem weltweit umfassendsten multimodalen Echtzeit-Datensatz basieren. Erfahren Sie mehr dar\u00fcber, wie project44 Unternehmen hilft, ihre komplexesten multimodalen Sichtbarkeitsherausforderungen zu l\u00f6sen <a href=\"http:\/\/www.project44.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.project44.com<\/a>. <\/p>\n\n<p class=\"wp-block-paragraph\">Gartner, Voice of the Customer f\u00fcr Echtzeit-Transportation-Transparenz-Plattformen, von Peer-Mitwirkenden, 31. Oktober 2023. <\/p>\n\n<p class=\"wp-block-paragraph\">GARTNER ist eine eingetragene Marke und Dienstleistungsmarke, und PEER INSIGHTS ist eine Marke und Dienstleistungsmarke von Gartner, Inc. und\/oder seinen assoziierten Unternehmen in den USA und international und werden hierin mit Genehmigung verwendet. Alle Rechte vorbehalten. <\/p>\n\n<p class=\"wp-block-paragraph\">1 <a href=\"https:\/\/blogs.gartner.com\/reviews-pages\/gartner-peer-insights-voice-of-the-customer-methodology-3-0\/%3E\" target=\"_blank\" rel=\"noreferrer noopener\">Gartner Peer Insights Voice of the Customer-Methodik<\/a>, 2. November 2023, &lt;<a href=\"https:\/\/blogs.gartner.com\/reviews-pages\/gartner-peer-insights-voice-of-the-customer-methodology-3-0\/\">https:\/\/blogs.gartner.com\/revi&#8230;<\/a>;<\/p>\n\n<p class=\"wp-block-paragraph\">Gartner Peer Insights-Inhalte bestehen aus den Meinungen einzelner Endbenutzer basierend auf ihren eigenen Erfahrungen mit den auf der Plattform aufgef\u00fchrten Anbietern. Sie sollten nicht als Tatsachenaussagen ausgelegt werden und repr\u00e4sentieren auch nicht die Ansichten von Gartner oder seinen verbundenen Unternehmen. Gartner unterst\u00fctzt keine Anbieter, Produkte oder Dienstleistungen, die in diesen Inhalten dargestellt werden, noch gibt Gartner ausdr\u00fcckliche oder stillschweigende Garantien in Bezug auf diese Inhalte \u00fcber ihre Genauigkeit oder Vollst\u00e4ndigkeit, einschlie\u00dflich Garantien der Marktg\u00e4ngigkeit oder Eignung f\u00fcr einen bestimmten Zweck. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Bericht, der direkte Benutzereinblicke in Echtzeit-Transport-Transparenz-Plattformen bietet, zeigt, dass 94\u00a0% der Benutzer bereit sind, project44 zu empfehlen. CHICAGO, 6. November 2023 &#8211;\u202fproject44, die f\u00fchrende Supply-Chain-Transparenz-Plattform, gab heute bekannt, dass&#8230;<\/p>\n","protected":false},"author":67,"featured_media":17513,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-41028","press-release","type-press-release","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Project44 wird im Gartner\u00ae Peer Insights\u2122 \u201eVoice of the Customer\u201c Bericht als \u201e2023 Customers\u2019 Choice\u201c bezeichnet | project44<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Project44 wird im Gartner\u00ae Peer Insights\u2122 \u201eVoice of the Customer\u201c Bericht als \u201e2023 Customers\u2019 Choice\u201c bezeichnet\" \/>\n<meta property=\"og:description\" content=\"Der Bericht, der direkte Benutzereinblicke in Echtzeit-Transport-Transparenz-Plattformen bietet, zeigt, dass 94\u00a0% der Benutzer bereit sind, project44 zu empfehlen. CHICAGO, 6. November 2023 &#8211;\u202fproject44, die f\u00fchrende Supply-Chain-Transparenz-Plattform, gab heute bekannt, dass...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/\" \/>\n<meta property=\"og:site_name\" content=\"project44\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/project44Visibility\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-06T16:27:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.project44.com\/wp-content\/uploads\/2024\/02\/Untitled-design-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2720\" \/>\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@freightpipes\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/press-releases\\\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\\\/\",\"url\":\"https:\\\/\\\/www.project44.com\\\/de\\\/press-releases\\\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\\\/\",\"name\":\"Project44 wird im Gartner\u00ae Peer Insights\u2122 \u201eVoice of the Customer\u201c Bericht als \u201e2023 Customers\u2019 Choice\u201c bezeichnet | project44\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/press-releases\\\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/press-releases\\\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.project44.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Untitled-design-5.png\",\"datePublished\":\"2023-11-06T17:46:00+00:00\",\"dateModified\":\"2024-09-06T16:27:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/press-releases\\\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.project44.com\\\/de\\\/press-releases\\\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/press-releases\\\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.project44.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Untitled-design-5.png\",\"contentUrl\":\"https:\\\/\\\/www.project44.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Untitled-design-5.png\",\"width\":2720,\"height\":1700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/press-releases\\\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.project44.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Project44 wird im Gartner\u00ae Peer Insights\u2122 \u201eVoice of the Customer\u201c Bericht als \u201e2023 Customers\u2019 Choice\u201c bezeichnet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.project44.com\\\/de\\\/\",\"name\":\"project44\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.project44.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/#organization\",\"name\":\"project44\",\"url\":\"https:\\\/\\\/www.project44.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.project44.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.project44.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo.svg\",\"width\":213,\"height\":73,\"caption\":\"project44\"},\"image\":{\"@id\":\"https:\\\/\\\/www.project44.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/project44Visibility\",\"https:\\\/\\\/x.com\\\/freightpipes\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/project-44\",\"https:\\\/\\\/www.instagram.com\\\/project44global\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Project44 wird im Gartner\u00ae Peer Insights\u2122 \u201eVoice of the Customer\u201c Bericht als \u201e2023 Customers\u2019 Choice\u201c bezeichnet | project44","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/","og_locale":"de_DE","og_type":"article","og_title":"Project44 wird im Gartner\u00ae Peer Insights\u2122 \u201eVoice of the Customer\u201c Bericht als \u201e2023 Customers\u2019 Choice\u201c bezeichnet","og_description":"Der Bericht, der direkte Benutzereinblicke in Echtzeit-Transport-Transparenz-Plattformen bietet, zeigt, dass 94\u00a0% der Benutzer bereit sind, project44 zu empfehlen. CHICAGO, 6. November 2023 &#8211;\u202fproject44, die f\u00fchrende Supply-Chain-Transparenz-Plattform, gab heute bekannt, dass...","og_url":"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/","og_site_name":"project44","article_publisher":"https:\/\/www.facebook.com\/project44Visibility","article_modified_time":"2024-09-06T16:27:03+00:00","og_image":[{"width":2720,"height":1700,"url":"https:\/\/www.project44.com\/wp-content\/uploads\/2024\/02\/Untitled-design-5.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@freightpipes","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/","url":"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/","name":"Project44 wird im Gartner\u00ae Peer Insights\u2122 \u201eVoice of the Customer\u201c Bericht als \u201e2023 Customers\u2019 Choice\u201c bezeichnet | project44","isPartOf":{"@id":"https:\/\/www.project44.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/#primaryimage"},"image":{"@id":"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.project44.com\/wp-content\/uploads\/2024\/02\/Untitled-design-5.png","datePublished":"2023-11-06T17:46:00+00:00","dateModified":"2024-09-06T16:27:03+00:00","breadcrumb":{"@id":"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/#primaryimage","url":"https:\/\/www.project44.com\/wp-content\/uploads\/2024\/02\/Untitled-design-5.png","contentUrl":"https:\/\/www.project44.com\/wp-content\/uploads\/2024\/02\/Untitled-design-5.png","width":2720,"height":1700},{"@type":"BreadcrumbList","@id":"https:\/\/www.project44.com\/de\/press-releases\/project44-wird-im-gartner-peer-insights-voice-of-the-customer-bericht-als-2023-customers-choice-bezeichnet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.project44.com\/de\/"},{"@type":"ListItem","position":2,"name":"Project44 wird im Gartner\u00ae Peer Insights\u2122 \u201eVoice of the Customer\u201c Bericht als \u201e2023 Customers\u2019 Choice\u201c bezeichnet"}]},{"@type":"WebSite","@id":"https:\/\/www.project44.com\/de\/#website","url":"https:\/\/www.project44.com\/de\/","name":"project44","description":"","publisher":{"@id":"https:\/\/www.project44.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.project44.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.project44.com\/de\/#organization","name":"project44","url":"https:\/\/www.project44.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.project44.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.project44.com\/wp-content\/uploads\/2024\/01\/logo.svg","contentUrl":"https:\/\/www.project44.com\/wp-content\/uploads\/2024\/01\/logo.svg","width":213,"height":73,"caption":"project44"},"image":{"@id":"https:\/\/www.project44.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/project44Visibility","https:\/\/x.com\/freightpipes","https:\/\/www.linkedin.com\/company\/project-44","https:\/\/www.instagram.com\/project44global"]}]}},"_links":{"self":[{"href":"https:\/\/www.project44.com\/de\/wp-json\/wp\/v2\/press-release\/41028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.project44.com\/de\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/www.project44.com\/de\/wp-json\/wp\/v2\/types\/press-release"}],"author":[{"embeddable":true,"href":"https:\/\/www.project44.com\/de\/wp-json\/wp\/v2\/users\/67"}],"version-history":[{"count":0,"href":"https:\/\/www.project44.com\/de\/wp-json\/wp\/v2\/press-release\/41028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.project44.com\/de\/wp-json\/wp\/v2\/media\/17513"}],"wp:attachment":[{"href":"https:\/\/www.project44.com\/de\/wp-json\/wp\/v2\/media?parent=41028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}